{"id":4,"count":12,"description":"","link":"https:\/\/halicium.com\/index.php\/category\/gaya-desain\/","name":"Gaya Desain","slug":"gaya-desain","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/halicium.com\/index.php\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/halicium.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/halicium.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/halicium.com\/index.php\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}